{"id":80,"date":"2015-11-15T15:21:50","date_gmt":"2015-11-15T15:21:50","guid":{"rendered":"http:\/\/127.0.0.1\/mazda\/?p=80"},"modified":"2019-09-20T15:41:56","modified_gmt":"2019-09-20T08:41:56","slug":"mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/","title":{"rendered":"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"<p><strong>\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34\u0e41\u0e2d\u0e04\u0e17\u0e23\u0e32\u0e08 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e36\u0e49\u0e07<\/strong><\/p>\n<div class=\"video-container car-vdo\"><iframe src=\"https:\/\/www.youtube.com\/embed\/ClUy8jY91rU\" width=\"70%\" height=\"50%\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n<div class=\"video-container car-vdo\"><\/div>\n<div class=\"video-container car-vdo\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34\u0e41\u0e2d\u0e04\u0e17\u0e23\u0e32\u0e08 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e36\u0e49\u0e07<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-80","post","type-post","status-publish","format-standard","hentry","category-vdo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\u0e08\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49-1000-mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34\u0e41\u0e2d\u0e04\u0e17\u0e23\u0e32\u0e08 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e36\u0e49\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\u0e08\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49-1000-mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-15T15:21:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-20T08:41:56+00:00\" \/>\n<meta name=\"author\" content=\"Ch.Erawan Happy Service\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ch.Erawan Happy Service\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/\",\"url\":\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/\",\"name\":\"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"isPartOf\":{\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/#website\"},\"datePublished\":\"2015-11-15T15:21:50+00:00\",\"dateModified\":\"2019-09-20T08:41:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/0e57f522e7d730a8b3e15e0912a8248f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ch-erawan.com\/mitsu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/#website\",\"url\":\"https:\/\/www.ch-erawan.com\/mitsu\/\",\"name\":\"\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"description\":\"\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e16\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e42\u0e17\u0e23. 063-445-3444 | \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ch-erawan.com\/mitsu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/0e57f522e7d730a8b3e15e0912a8248f\",\"name\":\"Ch.Erawan Happy Service\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/41b286dff086c04f355c078ada9964297d0f13a1c929720c572e191fa98b726a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/41b286dff086c04f355c078ada9964297d0f13a1c929720c572e191fa98b726a?s=96&d=mm&r=g\",\"caption\":\"Ch.Erawan Happy Service\"},\"url\":\"https:\/\/www.ch-erawan.com\/mitsu\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\u0e08\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49-1000-mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","og_description":"\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34\u0e41\u0e2d\u0e04\u0e17\u0e23\u0e32\u0e08 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e36\u0e49\u0e07","og_url":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\u0e08\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49-1000-mazda-cx-5-skyactiv-\u0e17\u0e33\u0e22\u0e2d\u0e14\/","og_site_name":"\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","article_published_time":"2015-11-15T15:21:50+00:00","article_modified_time":"2019-09-20T08:41:56+00:00","author":"Ch.Erawan Happy Service","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ch.Erawan Happy Service"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/","url":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/","name":"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48 - \u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","isPartOf":{"@id":"https:\/\/www.ch-erawan.com\/mitsu\/#website"},"datePublished":"2015-11-15T15:21:50+00:00","dateModified":"2019-09-20T08:41:56+00:00","author":{"@id":"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/0e57f522e7d730a8b3e15e0912a8248f"},"breadcrumb":{"@id":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ch-erawan.com\/mitsu\/mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%88%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%81%e0%b8%a5%e0%b9%89-1000-mazda-cx-5-skyactiv-%e0%b8%97%e0%b8%b3%e0%b8%a2%e0%b8%ad%e0%b8%94\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ch-erawan.com\/mitsu\/"},{"@type":"ListItem","position":2,"name":"\u0e21\u0e32\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e01\u0e31\u0e1a \u0e21\u0e34\u0e15\u0e0b\u0e39\u0e1a\u0e34\u0e0a\u0e34 \u0e41\u0e2d\u0e17\u0e17\u0e23\u0e32\u0e08 \u0e43\u0e2b\u0e21\u0e48"}]},{"@type":"WebSite","@id":"https:\/\/www.ch-erawan.com\/mitsu\/#website","url":"https:\/\/www.ch-erawan.com\/mitsu\/","name":"\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e0a.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","description":"\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e16\u0e21\u0e34\u0e15\u0e0b\u0e39 \u0e42\u0e17\u0e23. 063-445-3444 | \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e21\u0e34\u0e15\u0e0b\u0e39\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ch-erawan.com\/mitsu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/0e57f522e7d730a8b3e15e0912a8248f","name":"Ch.Erawan Happy Service","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.ch-erawan.com\/mitsu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/41b286dff086c04f355c078ada9964297d0f13a1c929720c572e191fa98b726a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41b286dff086c04f355c078ada9964297d0f13a1c929720c572e191fa98b726a?s=96&d=mm&r=g","caption":"Ch.Erawan Happy Service"},"url":"https:\/\/www.ch-erawan.com\/mitsu\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":23,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"predecessor-version":[{"id":2280,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/posts\/80\/revisions\/2280"}],"wp:attachment":[{"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ch-erawan.com\/mitsu\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}